

{"id":3280,"date":"2023-03-20T19:05:51","date_gmt":"2023-03-20T19:05:51","guid":{"rendered":"https:\/\/bada-bing.ro\/brasov\/?page_id=3280"},"modified":"2025-07-05T12:53:23","modified_gmt":"2025-07-05T09:53:23","slug":"bada-bing","status":"publish","type":"page","link":"https:\/\/bada-bing.ro\/brasov\/","title":{"rendered":"Bada Bing"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row sticker_svg_path=&#8221;&#8221; css=&#8221;.vc_custom_1688809733991{margin-top: 50px !important;}&#8221; el_class=&#8221;pizzaProduct&#8221;][vc_column][vc_empty_space height=&#8221;1px&#8221; el_id=&#8221;oferte&#8221; el_class=&#8221;section-anchor&#8221;][vc_custom_heading text=&#8221;Oferte&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; google_fonts=&#8221;font_family:Open%20Sans%3A300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C800%2C800italic|font_style:800%20bold%20regular%3A800%3Anormal&#8221;]<div class=\"qodef-pl-holder qodef-grid-list qodef-disable-bottom-space qodef-standard-layout qodef-four-columns qodef-small-space qodef-info-below-image    qodef-filter-separator-enabled\"  data-type=standard data-info-position=info-below-image data-number-of-posts=99999999 data-number-of-columns=four data-space-between-items=small data-orderby=date data-order=ASC data-show-category-filter=no data-disable-filter-separator=no data-taxonomy-to-display=category data-taxonomy-values=Oferta data-show-all-item-in-filter=yes data-products-in-grid=yes data-display-title=yes data-title-tag=h5 data-display-category=no data-display-excerpt=yes data-excerpt-length=20 data-display-rating=no data-display-price=yes data-display-button=yes data-bg-image=no data-button-skin=default data-class-name=pli data-max-num-pages=1 data-next-page=2>\n            <div class=\"qodef-prl-loading\">\n        <div class=\"qodef-peppe-spinner-image\">\n<!--            -->        <\/div>\n    <\/div>\n\t<div class=\"qodef-pl-outer qodef-outer-space qodef-row-grid-section\">\n        <div class=\"qodef-outer-space\">\n            <div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"390\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyemiliana-600x390.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyemiliana-600x390.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyemiliana-300x195.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyemiliana-768x499.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyemiliana.webp 862w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>            <div class=\"badgeCustom\">Oferta<\/div><div class=\"ofertatext\">+3 sucuri GRATUITE la 0,33l!<\/div>            <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-emiliana\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-emiliana\/\">Party Emiliana<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.900g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, \u0219unc\u0103, salam uscat, mu\u0219chi file, specialitate baco...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">103,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-emiliana\/\" data-quantity=\"1\" data-product_id=\"3347\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3347\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"390\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partycarciofina-600x390.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partycarciofina-600x390.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partycarciofina-300x195.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partycarciofina-768x499.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partycarciofina.webp 862w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>            <div class=\"badgeCustom\">Oferta<\/div><div class=\"ofertatext\">+3 sucuri GRATUITE la 0,33l!<\/div>            <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-carciofina\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-carciofina\/\">Party Carciofina<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.750g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, mu\u0219chi file, salam de var\u0103, salam Chorizo, ciuperci...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">102,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-carciofina\/\" data-quantity=\"1\" data-product_id=\"3357\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3357\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"407\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyporcelina-600x407.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyporcelina-600x407.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyporcelina-300x203.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyporcelina-768x521.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyporcelina.webp 826w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>            <div class=\"badgeCustom\">Oferta<\/div><div class=\"ofertatext\">+3 sucuri GRATUITE la 0,33l!<\/div>            <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-porcelina\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-porcelina\/\">Party Porcelina<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.900g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, \u0219unc\u0103, salam de var\u0103, salam Chorizo, salam uscat, ...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">103,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-porcelina\/\" data-quantity=\"1\" data-product_id=\"3359\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3359\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"402\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partytonno-600x402.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partytonno-600x402.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partytonno-300x201.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partytonno-768x515.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partytonno.webp 835w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>            <div class=\"badgeCustom\">Oferta<\/div><div class=\"ofertatext\">+3 sucuri GRATUITE la 0,33l!<\/div>            <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-tonno\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-tonno\/\">Party Tonno<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.750g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, ton buc\u0103\u021bi \u00een suc propriu, ceap\u0103, l\u0103m\u00e2ie, m\u0103sl...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">102,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-tonno\/\" data-quantity=\"1\" data-product_id=\"3381\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3381\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>        <\/div>\n\t<\/div>\n<\/div>[\/vc_column][\/vc_row][vc_row sticker_svg_path=&#8221;&#8221; css=&#8221;.vc_custom_1751398121146{margin-top: 50px !important;}&#8221; el_class=&#8221;pizzaProduct&#8221;][vc_column][vc_empty_space height=&#8221;1px&#8221; el_id=&#8221;partytitan&#8221; el_class=&#8221;section-anchor&#8221;][vc_custom_heading text=&#8221;PIZZA PARTY TITAN (60&#215;80 cm | 10-14 persoane)&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; google_fonts=&#8221;font_family:Open%20Sans%3A300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C800%2C800italic|font_style:800%20bold%20regular%3A800%3Anormal&#8221;]<div class=\"qodef-pl-holder qodef-grid-list qodef-disable-bottom-space qodef-standard-layout qodef-four-columns qodef-small-space qodef-info-below-image    qodef-filter-separator-enabled\"  data-type=standard data-info-position=info-below-image data-number-of-posts=99999999 data-number-of-columns=four data-space-between-items=small data-orderby=date data-order=ASC data-show-category-filter=no data-disable-filter-separator=no data-taxonomy-to-display=category data-taxonomy-values=PartyTitan data-show-all-item-in-filter=yes data-products-in-grid=yes data-display-title=yes data-title-tag=h5 data-display-category=no data-display-excerpt=yes data-excerpt-length=20 data-display-rating=no data-display-price=yes data-display-button=yes data-bg-image=no data-button-skin=default data-class-name=pli data-max-num-pages=1 data-next-page=2>\n            <div class=\"qodef-prl-loading\">\n        <div class=\"qodef-peppe-spinner-image\">\n<!--            -->        <\/div>\n    <\/div>\n\t<div class=\"qodef-pl-outer qodef-outer-space qodef-row-grid-section\">\n        <div class=\"qodef-outer-space\">\n            <div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"414\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2025\/04\/party_titan_universo-600x414.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2025\/04\/party_titan_universo-600x414.jpg 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2025\/04\/party_titan_universo-300x207.jpg 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2025\/04\/party_titan_universo.jpg 704w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-titan-universo\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-titan-universo\/\">Party Titan Universo<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        3900g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        1\/3 - topping pizza First\/mozzarella, sos de ro\u0219ii, \u0219unc\u0103, ciuperci, mu\u0219chi file, salam de var\u0103...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">164,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-titan-universo\/\" data-quantity=\"1\" data-product_id=\"24679\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"24679\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"413\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2025\/04\/party_titan_galaxy-600x413.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2025\/04\/party_titan_galaxy-600x413.jpg 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2025\/04\/party_titan_galaxy-300x207.jpg 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2025\/04\/party_titan_galaxy.jpg 704w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-titan-galaxy\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-titan-galaxy\/\">Party Titan Galaxy<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        4100g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        1\/2 - topping pizza First\/mozzarella, sos de ro\u0219ii, ciuperci, \u0219unc\u0103, m\u0103sline negre \u00eentregi, por...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">164,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-titan-galaxy\/\" data-quantity=\"1\" data-product_id=\"24674\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"24674\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"414\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2025\/04\/party_titan_bigbang-600x414.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2025\/04\/party_titan_bigbang-600x414.jpg 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2025\/04\/party_titan_bigbang-300x207.jpg 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2025\/04\/party_titan_bigbang.jpg 704w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-titan-big-bang\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-titan-big-bang\/\">Party Titan Big Bang<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        3700g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        1\/4 - topping pizza First\/mozzarella, sos de ro\u0219ii, \u0219unc\u0103, porumb, m\u0103sline\r\n\r\n1\/4 - topping pizz...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">164,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-titan-big-bang\/\" data-quantity=\"1\" data-product_id=\"24681\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"24681\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>        <\/div>\n\t<\/div>\n<\/div>[\/vc_column][\/vc_row][vc_row sticker_svg_path=&#8221;&#8221; css=&#8221;.vc_custom_1751398121146{margin-top: 50px !important;}&#8221; el_class=&#8221;pizzaProduct&#8221;][vc_column][vc_empty_space height=&#8221;1px&#8221; el_id=&#8221;pizzaparty&#8221; el_class=&#8221;section-anchor&#8221;][vc_custom_heading text=&#8221;PIZZA PARTY (40&#215;60 cm | 5-6 persoane)&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; google_fonts=&#8221;font_family:Open%20Sans%3A300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C800%2C800italic|font_style:800%20bold%20regular%3A800%3Anormal&#8221;]<div class=\"qodef-pl-holder qodef-grid-list qodef-disable-bottom-space qodef-standard-layout qodef-four-columns qodef-small-space qodef-info-below-image    qodef-filter-separator-enabled\"  data-type=standard data-info-position=info-below-image data-number-of-posts=99999999 data-number-of-columns=four data-space-between-items=small data-orderby=date data-order=ASC data-show-category-filter=no data-disable-filter-separator=no data-taxonomy-to-display=category data-taxonomy-values=PizzaParty data-show-all-item-in-filter=yes data-products-in-grid=yes data-display-title=yes data-title-tag=h5 data-display-category=no data-display-excerpt=yes data-excerpt-length=20 data-display-rating=no data-display-price=yes data-display-button=yes data-bg-image=no data-button-skin=default data-class-name=pli data-max-num-pages=1 data-next-page=2>\n            <div class=\"qodef-prl-loading\">\n        <div class=\"qodef-peppe-spinner-image\">\n<!--            -->        <\/div>\n    <\/div>\n\t<div class=\"qodef-pl-outer qodef-outer-space qodef-row-grid-section\">\n        <div class=\"qodef-outer-space\">\n            <div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"404\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partymargherita-600x404.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partymargherita-600x404.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partymargherita-300x202.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partymargherita-768x518.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partymargherita.webp 831w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-margherita\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-margherita\/\">Party Margherita<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.400g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        extra topping pizza First\/mozzarella, sos de ro\u0219ii\r\nAlergeni: Gluten, Lapte, \u021aelin\u0103\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">77,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-margherita\/\" data-quantity=\"1\" data-product_id=\"3341\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3341\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partycarnivora-2-600x400.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partycarnivora-2-600x400.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partycarnivora-2-300x200.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partycarnivora-2-768x512.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partycarnivora-2.webp 840w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-carnivora\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-carnivora\/\">Party Carnivora<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.900g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, \u0219unc\u0103, ciuperci, mu\u0219chi file, salam de var\u0103, caba...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">90,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-carnivora\/\" data-quantity=\"1\" data-product_id=\"3343\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3343\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"390\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyemiliana-600x390.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyemiliana-600x390.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyemiliana-300x195.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyemiliana-768x499.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyemiliana.webp 862w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>            <div class=\"badgeCustom\">Oferta<\/div><div class=\"ofertatext\">+3 sucuri GRATUITE la 0,33l!<\/div>            <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-emiliana\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-emiliana\/\">Party Emiliana<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.900g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, \u0219unc\u0103, salam uscat, mu\u0219chi file, specialitate baco...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">103,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-emiliana\/\" data-quantity=\"1\" data-product_id=\"3347\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3347\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"388\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyroyal-2-600x388.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyroyal-2-600x388.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyroyal-2-300x194.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyroyal-2-768x497.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyroyal-2.webp 866w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-royal\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-royal\/\">Party Royal<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        2.200g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, \u0219unc\u0103, jambon, salam b\u0103n\u0103\u021bean, ciuperci, porumb ...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">91,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-royal\/\" data-quantity=\"1\" data-product_id=\"3349\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3349\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partycapriciosa-2-600x400.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partycapriciosa-2-600x400.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partycapriciosa-2-300x200.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partycapriciosa-2-768x512.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partycapriciosa-2.webp 840w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-capriciosa\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-capriciosa\/\">Party Capriciosa<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.550g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, ciuperci, \u0219unc\u0103, m\u0103sline negre \u00eentregi\r\nAlergeni:...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">82,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-capriciosa\/\" data-quantity=\"1\" data-product_id=\"3351\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3351\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"398\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyprosciuttosalami-600x398.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyprosciuttosalami-600x398.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyprosciuttosalami-300x199.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyprosciuttosalami-768x510.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyprosciuttosalami.webp 844w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-prosciutto-salami\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-prosciutto-salami\/\">Party Prosciutto Salami<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.600g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, \u0219unc\u0103, m\u0103sline negre \u00eentregi, salam uscat\r\nAlerge...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">83,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-prosciutto-salami\/\" data-quantity=\"1\" data-product_id=\"3353\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3353\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partydeluxe-2-600x400.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partydeluxe-2-600x400.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partydeluxe-2-300x200.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partydeluxe-2-768x512.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partydeluxe-2.webp 840w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-deluxe\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-deluxe\/\">Party Deluxe<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        2.100g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, \u0219unc\u0103, salam uscat, specialitate bacon, piept de pu...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">97,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-deluxe\/\" data-quantity=\"1\" data-product_id=\"3355\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3355\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"390\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partycarciofina-600x390.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partycarciofina-600x390.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partycarciofina-300x195.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partycarciofina-768x499.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partycarciofina.webp 862w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>            <div class=\"badgeCustom\">Oferta<\/div><div class=\"ofertatext\">+3 sucuri GRATUITE la 0,33l!<\/div>            <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-carciofina\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-carciofina\/\">Party Carciofina<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.750g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, mu\u0219chi file, salam de var\u0103, salam Chorizo, ciuperci...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">102,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-carciofina\/\" data-quantity=\"1\" data-product_id=\"3357\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3357\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"407\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyporcelina-600x407.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyporcelina-600x407.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyporcelina-300x203.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyporcelina-768x521.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyporcelina.webp 826w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>            <div class=\"badgeCustom\">Oferta<\/div><div class=\"ofertatext\">+3 sucuri GRATUITE la 0,33l!<\/div>            <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-porcelina\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-porcelina\/\">Party Porcelina<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.900g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, \u0219unc\u0103, salam de var\u0103, salam Chorizo, salam uscat, ...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">103,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-porcelina\/\" data-quantity=\"1\" data-product_id=\"3359\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3359\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"396\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partybadabing-600x396.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partybadabing-600x396.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partybadabing-300x198.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partybadabing-768x507.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partybadabing.webp 848w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-bada-bing\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-bada-bing\/\">Party Bada Bing<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.600g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, ceaf\u0103 afumat\u0103, ro\u0219ii felii, ardei gras\r\nAlergeni: ...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">87,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-bada-bing\/\" data-quantity=\"1\" data-product_id=\"3361\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3361\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partysuprema-600x400.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partysuprema-600x400.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partysuprema-300x200.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partysuprema-768x512.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partysuprema.webp 840w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-suprema\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-suprema\/\">Party Suprema<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        2.200g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, ciuperci, \u0219unc\u0103, m\u0103sline negre \u00eentregi, porumb (p...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">95,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-suprema\/\" data-quantity=\"1\" data-product_id=\"3363\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3363\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"391\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyquatrostagioni-3-600x391.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyquatrostagioni-3-600x391.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyquatrostagioni-3-300x196.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyquatrostagioni-3-768x501.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyquatrostagioni-3.webp 859w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-quatro-stagioni\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-quatro-stagioni\/\">Party Quatro Stagioni<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.600g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, ciuperci, \u0219unc\u0103, porumb (produs congelat), m\u0103sline...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">83,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-quatro-stagioni\/\" data-quantity=\"1\" data-product_id=\"3365\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3365\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partymultipizza-2-600x400.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partymultipizza-2-600x400.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partymultipizza-2-300x200.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partymultipizza-2-768x511.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partymultipizza-2.webp 841w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-multipizza\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-multipizza\/\">Party Multipizza<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        2.000g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, ciuperci, \u0219unc\u0103, m\u0103sline negre \u00eentregi, porumb (p...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">91,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-multipizza\/\" data-quantity=\"1\" data-product_id=\"3367\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3367\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"385\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyquatrostagionicuceapa-600x385.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyquatrostagionicuceapa-600x385.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyquatrostagionicuceapa-300x193.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyquatrostagionicuceapa-768x493.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyquatrostagionicuceapa.webp 872w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-quatro-stagioni-cu-ceapa\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-quatro-stagioni-cu-ceapa\/\">Party Quatro Stagioni cu ceap\u0103<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.630g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, ciuperci, \u0219unc\u0103, porumb (produs congelat), m\u0103sline...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">84,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-quatro-stagioni-cu-ceapa\/\" data-quantity=\"1\" data-product_id=\"3373\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3373\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"395\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/bada-bada-02382-600x395.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/bada-bada-02382-600x395.jpg 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/bada-bada-02382-300x198.jpg 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/bada-bada-02382-1024x675.jpg 1024w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/bada-bada-02382-768x506.jpg 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/bada-bada-02382-1536x1012.jpg 1536w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-3-formagio-2\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-3-formagio-2\/\">Party Quatro Formagio<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.600g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        extra topping pizza First\/mozzarella, sos de ro\u0219ii, telemea, parmezan, gorgonzola, ro\u0219ii felii\r\nAl...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">87,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-3-formagio-2\/\" data-quantity=\"1\" data-product_id=\"3375\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3375\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"404\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyspeciala-2-600x404.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyspeciala-2-600x404.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyspeciala-2-300x202.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyspeciala-2-768x517.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyspeciala-2.webp 832w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-speciala\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-speciala\/\">Party Speciala<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.850g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, \u0219unc\u0103, ardei gras, porumb (produs congelat), legume...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">90,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-speciala\/\" data-quantity=\"1\" data-product_id=\"3377\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3377\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyprosciuttofunghi-2-600x400.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyprosciuttofunghi-2-600x400.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyprosciuttofunghi-2-300x200.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyprosciuttofunghi-2-768x512.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyprosciuttofunghi-2.webp 840w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-prosciutto-e-funghi\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-prosciutto-e-funghi\/\">Party Prosciutto e Funghi<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.500g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, ciuperci, \u0219unc\u0103\r\nAlergeni: Gluten, Lapte, \u021aelin\u0103\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">79,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-prosciutto-e-funghi\/\" data-quantity=\"1\" data-product_id=\"3379\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3379\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"402\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partytonno-600x402.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partytonno-600x402.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partytonno-300x201.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partytonno-768x515.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partytonno.webp 835w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>            <div class=\"badgeCustom\">Oferta<\/div><div class=\"ofertatext\">+3 sucuri GRATUITE la 0,33l!<\/div>            <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-tonno\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-tonno\/\">Party Tonno<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.750g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, ton buc\u0103\u021bi \u00een suc propriu, ceap\u0103, l\u0103m\u00e2ie, m\u0103sl...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">102,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-tonno\/\" data-quantity=\"1\" data-product_id=\"3381\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3381\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyvegetariana-3-600x400.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyvegetariana-3-600x400.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyvegetariana-3-300x200.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyvegetariana-3-768x512.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyvegetariana-3.webp 840w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-vegetariana\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-vegetariana\/\">Party Vegetariana<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        2.000g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, ciuperci, legume mexicane (produs congelat), m\u0103sline...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">90,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-vegetariana\/\" data-quantity=\"1\" data-product_id=\"3385\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3385\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partypollo-2-600x400.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partypollo-2-600x400.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partypollo-2-300x200.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partypollo-2-768x512.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partypollo-2.webp 840w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-pollo\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-pollo\/\">Party Pollo<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.600g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, piept de pui (produs congelat), ro\u0219ii felii, m\u0103slin...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">86,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-pollo\/\" data-quantity=\"1\" data-product_id=\"3387\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3387\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"393\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyprosciuttomuschiulet-2-600x393.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyprosciuttomuschiulet-2-600x393.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyprosciuttomuschiulet-2-300x197.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyprosciuttomuschiulet-2-768x504.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partyprosciuttomuschiulet-2.webp 854w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-prosciutto-muschiulet\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-prosciutto-muschiulet\/\">Party Prosciutto Mu\u0219chiule\u021b<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.700g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, \u0219unc\u0103, mu\u0219chi file\r\nAlergeni: Gluten, Lapte, \u021aeli...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">86,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-prosciutto-muschiulet\/\" data-quantity=\"1\" data-product_id=\"3389\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3389\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"409\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partybrasoveana-600x409.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partybrasoveana-600x409.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partybrasoveana-300x204.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partybrasoveana-768x523.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partybrasoveana.webp 822w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-brasoveana\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-brasoveana\/\">Party Bra\u0219ovean\u0103<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.750g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, ciuperci, \u0219unc\u0103, porumb (produs congelat), m\u0103sline...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">87,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-brasoveana\/\" data-quantity=\"1\" data-product_id=\"3391\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3391\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"396\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partypicanta-600x396.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partypicanta-600x396.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partypicanta-300x198.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partypicanta-768x507.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partypicanta.webp 849w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-picanta\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-picanta\/\">Party Picant\u0103<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.700g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos picant, salam uscat picant, \u0219unc\u0103, ardei iute\r\nAlergeni: Glute...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">85,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-picanta\/\" data-quantity=\"1\" data-product_id=\"3393\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3393\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partytaraneasca-2-600x400.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partytaraneasca-2-600x400.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partytaraneasca-2-300x200.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partytaraneasca-2-768x512.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partytaraneasca-2.webp 840w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-taraneasca\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-taraneasca\/\">Party \u021a\u0103r\u0103neasc\u0103<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.700g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, \u0219unc\u0103, cabanos, ceap\u0103, porumb (produs congelat), a...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">86,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-taraneasca\/\" data-quantity=\"1\" data-product_id=\"3395\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3395\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partychickendeluxe-2-600x400.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partychickendeluxe-2-600x400.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partychickendeluxe-2-300x200.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partychickendeluxe-2-768x512.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/partychickendeluxe-2.webp 840w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-chicken-deluxe\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-chicken-deluxe\/\">Party Chicken Deluxe<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        2.200g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, ciuperci, porumb (produs congelat), m\u0103sline, piept d...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">93,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-chicken-deluxe\/\" data-quantity=\"1\" data-product_id=\"3397\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3397\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/07\/partyrustica-2-600x400.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/07\/partyrustica-2-600x400.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/07\/partyrustica-2-300x200.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/07\/partyrustica-2-768x512.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/07\/partyrustica-2.webp 840w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-rustica\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-rustica\/\">Party Rustic\u0103<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.750g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, specialitate bacon, ciuperci, ardei iute, ardei gras,...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                                        <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">88,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/party-rustica\/\" data-quantity=\"1\" data-product_id=\"3399\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3399\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>        <\/div>\n\t<\/div>\n<\/div>[\/vc_column][\/vc_row][vc_row sticker_svg_path=&#8221;&#8221; css=&#8221;.vc_custom_1751398115668{margin-top: 50px !important;}&#8221; el_class=&#8221;pizzaProduct&#8221;][vc_column][vc_empty_space height=&#8221;1px&#8221; el_id=&#8221;pizzafamily&#8221; el_class=&#8221;section-anchor&#8221;][vc_custom_heading text=&#8221;PIZZA FAMILY (diametru 45 cm | 3-4 persoane)&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; google_fonts=&#8221;font_family:Open%20Sans%3A300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C800%2C800italic|font_style:800%20bold%20regular%3A800%3Anormal&#8221;]<div class=\"qodef-pl-holder qodef-grid-list qodef-disable-bottom-space qodef-standard-layout qodef-four-columns qodef-small-space qodef-info-below-image    qodef-filter-separator-enabled\"  data-type=standard data-info-position=info-below-image data-number-of-posts=99999999 data-number-of-columns=four data-space-between-items=small data-orderby=date data-order=DESC data-show-category-filter=no data-disable-filter-separator=no data-taxonomy-to-display=category data-taxonomy-values=PizzaFamily data-show-all-item-in-filter=yes data-products-in-grid=yes data-display-title=yes data-title-tag=h5 data-display-category=no data-display-excerpt=no data-excerpt-length=20 data-display-rating=yes data-display-price=yes data-display-button=yes data-bg-image=no data-button-skin=default data-class-name=pli data-max-num-pages=1 data-next-page=2>\n            <div class=\"qodef-prl-loading\">\n        <div class=\"qodef-peppe-spinner-image\">\n<!--            -->        <\/div>\n    <\/div>\n\t<div class=\"qodef-pl-outer qodef-outer-space qodef-row-grid-section\">\n        <div class=\"qodef-outer-space\">\n            <div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"394\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familyprosciutto-600x394.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familyprosciutto-600x394.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familyprosciutto-300x197.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familyprosciutto-768x504.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familyprosciutto.webp 853w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-prosciutto\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-prosciutto\/\">Family Prosciutto<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.000g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, prosciutto crudo, rucola, parmezan\r\nAlergeni: Gluten,...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">59,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-prosciutto\/\" data-quantity=\"1\" data-product_id=\"3452\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3452\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familypomodoro-600x400.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familypomodoro-600x400.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familypomodoro-300x200.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familypomodoro-768x512.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familypomodoro.webp 840w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-pomodoro\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-pomodoro\/\">Family Pomodoro<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.250g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, mu\u0219chi file, m\u0103sline negre feliate, porumb (produs ...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">58,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-pomodoro\/\" data-quantity=\"1\" data-product_id=\"3450\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3450\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"423\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familymexicone-600x423.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familymexicone-600x423.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familymexicone-300x211.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familymexicone-768x541.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familymexicone.webp 795w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-mexiconi\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-mexiconi\/\">Family Mexiconi<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.300g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, mu\u0219chi file, jambon, anghinare, legume mexicane (pro...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">58,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-mexiconi\/\" data-quantity=\"1\" data-product_id=\"3448\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3448\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"387\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familypepperone-600x387.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familypepperone-600x387.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familypepperone-300x194.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familypepperone-768x495.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familypepperone.webp 868w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-peperone\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-peperone\/\">Family Peperone<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.350g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, mu\u0219chi file, salam de var\u0103, \u0219unc\u0103 Praga, pepperon...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">55,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-peperone\/\" data-quantity=\"1\" data-product_id=\"3446\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3446\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"402\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familycarcioso-600x402.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familycarcioso-600x402.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familycarcioso-300x201.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familycarcioso-768x514.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familycarcioso.webp 836w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-carcioso\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-carcioso\/\">Family Carcioso<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.250g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, salam uscat, \u0219unc\u0103 Praga, capere, anghinare, porumb...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">62,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-carcioso\/\" data-quantity=\"1\" data-product_id=\"3444\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3444\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"420\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familytonneli-600x420.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familytonneli-600x420.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familytonneli-300x210.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familytonneli-768x538.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familytonneli.webp 800w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-tonneli\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-tonneli\/\">Family Tonneli<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.300g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, ton buc\u0103\u021bi \u00een suc propriu, l\u0103m\u00e2ie, ceap\u0103\r\nAlerg...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">58,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-tonneli\/\" data-quantity=\"1\" data-product_id=\"3442\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3442\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"402\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familyoliva-600x402.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familyoliva-600x402.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familyoliva-300x201.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familyoliva-768x514.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familyoliva.webp 836w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-oliva\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-oliva\/\">Family Oliva<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.250g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, jambon, ciuperci, m\u0103sline verzi \u00eentregi, m\u0103sline n...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">58,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-oliva\/\" data-quantity=\"1\" data-product_id=\"3440\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3440\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"397\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familyjamboneli-600x397.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familyjamboneli-600x397.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familyjamboneli-300x199.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familyjamboneli-768x508.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familyjamboneli.webp 846w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-jamboneli\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-jamboneli\/\">Family Jamboneli<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.250g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, jambon, ciuperci, porumb (produs congelat), m\u0103sline ...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">58,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-jamboneli\/\" data-quantity=\"1\" data-product_id=\"3438\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3438\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familypolloricopolloloco-600x400.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familypolloricopolloloco-600x400.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familypolloricopolloloco-300x200.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familypolloricopolloloco-768x512.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familypolloricopolloloco.webp 840w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-pollorico-polloloco\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-pollorico-polloloco\/\">Family Pollorico Polloloco<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.400g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, piept de pui (produs congelat), \u0219unc\u0103 de pui, porum...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">58,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-pollorico-polloloco\/\" data-quantity=\"1\" data-product_id=\"3434\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3434\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"390\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familycapperi2-600x390.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familycapperi2-600x390.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familycapperi2-300x195.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familycapperi2-768x499.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familycapperi2.webp 862w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-capperi\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-capperi\/\">Family Capperi<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.300g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, mu\u0219chi file, capere, porumb (produs congelat), ardei...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">58,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-capperi\/\" data-quantity=\"1\" data-product_id=\"3432\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3432\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"399\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familybanateli-600x399.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familybanateli-600x399.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familybanateli-300x199.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familybanateli-768x510.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familybanateli.webp 843w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-banateli\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-banateli\/\">Family Banateli<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.300g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, \u0219unc\u0103 Praga, salam b\u0103n\u0103\u021bean, ciuperci, anghinare...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">58,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-banateli\/\" data-quantity=\"1\" data-product_id=\"3430\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3430\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familylolekbolek-600x400.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familylolekbolek-600x400.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familylolekbolek-300x200.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familylolekbolek-768x513.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/familylolekbolek.webp 839w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-lolek-si-bolek\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-lolek-si-bolek\/\">Family Lolek \u0219i Bolek<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        1.350g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, jambon, \u0219unc\u0103 Praga, ciuperci, porumb (produs conge...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">58,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/family-lolek-si-bolek\/\" data-quantity=\"1\" data-product_id=\"3427\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3427\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>        <\/div>\n\t<\/div>\n<\/div>[\/vc_column][\/vc_row][vc_row sticker_svg_path=&#8221;&#8221; css=&#8221;.vc_custom_1751398109724{margin-top: 50px !important;}&#8221; el_class=&#8221;pizzaProduct&#8221;][vc_column][vc_empty_space height=&#8221;1px&#8221; el_id=&#8221;pizzamica&#8221; el_class=&#8221;section-anchor&#8221;][vc_custom_heading text=&#8221;PIZZA MICA (diametru 28 cm)&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; google_fonts=&#8221;font_family:Open%20Sans%3A300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C800%2C800italic|font_style:800%20bold%20regular%3A800%3Anormal&#8221;]<div class=\"qodef-pl-holder qodef-grid-list qodef-disable-bottom-space qodef-standard-layout qodef-four-columns qodef-small-space qodef-info-below-image    qodef-filter-separator-enabled\"  data-type=standard data-info-position=info-below-image data-number-of-posts=99999 data-number-of-columns=four data-space-between-items=small data-orderby=date data-order=DESC data-show-category-filter=no data-disable-filter-separator=no data-taxonomy-to-display=category data-taxonomy-values=Pizzamica data-show-all-item-in-filter=yes data-products-in-grid=yes data-display-title=yes data-title-tag=h5 data-display-category=no data-display-excerpt=no data-excerpt-length=20 data-display-rating=yes data-display-price=yes data-display-button=yes data-bg-image=no data-button-skin=default data-class-name=pli data-max-num-pages=1 data-next-page=2>\n            <div class=\"qodef-prl-loading\">\n        <div class=\"qodef-peppe-spinner-image\">\n<!--            -->        <\/div>\n    <\/div>\n\t<div class=\"qodef-pl-outer qodef-outer-space qodef-row-grid-section\">\n        <div class=\"qodef-outer-space\">\n            <div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2026\/01\/pizzacapriciosa-600x400.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2026\/01\/pizzacapriciosa-600x400.jpg 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2026\/01\/pizzacapriciosa-300x200.jpg 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2026\/01\/pizzacapriciosa-768x512.jpg 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2026\/01\/pizzacapriciosa.jpg 840w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-capriciosa-460g\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-capriciosa-460g\/\">Pizza Capriciosa &#8211; 460g<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, ciuperci, \u0219unc\u0103, m\u0103sline negre \u00eentregi.&lt;br \/&g...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">31,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-capriciosa-460g\/\" data-quantity=\"1\" data-product_id=\"36472\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"36472\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaquatrostagioni-600x400.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaquatrostagioni-600x400.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaquatrostagioni-300x200.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaquatrostagioni-768x512.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaquatrostagioni.webp 840w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-quatro-stagioni\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-quatro-stagioni\/\">Pizza Quatro Stagioni<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        480g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, ciuperci, \u0219unc\u0103, porumb (produs congelat), m\u0103sline...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">31,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-quatro-stagioni\/\" data-quantity=\"1\" data-product_id=\"3496\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3496\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"373\" height=\"560\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzadiavolo.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzadiavolo.webp 373w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzadiavolo-200x300.webp 200w\" sizes=\"auto, (max-width: 373px) 100vw, 373px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-diavolo\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-diavolo\/\">Pizza Diavolo<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        420g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos picant, salam uscat picant, ardei iute\r\nAlergeni: Gluten, Soia, ...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">30,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-diavolo\/\" data-quantity=\"1\" data-product_id=\"3494\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3494\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzapollo-600x400.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzapollo-600x400.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzapollo-300x200.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzapollo-768x512.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzapollo.webp 840w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-pollo\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-pollo\/\">Pizza Pollo<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        420g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, piept de pui (produs congelat), ro\u0219ii felii\r\nAlergen...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">30,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-pollo\/\" data-quantity=\"1\" data-product_id=\"3492\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3492\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"406\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzavegetariana-600x406.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzavegetariana-600x406.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzavegetariana-300x203.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzavegetariana-768x520.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzavegetariana.webp 827w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-vegetariana\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-vegetariana\/\">Pizza Vegetarian\u0103<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        550g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, ciuperci, legume mexicane (produs congelat), m\u0103sline...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">31,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-vegetariana\/\" data-quantity=\"1\" data-product_id=\"3490\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3490\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"415\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzabrasoveana-600x415.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzabrasoveana-600x415.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzabrasoveana-300x207.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzabrasoveana-768x531.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzabrasoveana.webp 810w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-brasoveana\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-brasoveana\/\">Pizza Bra\u0219ovean\u0103<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        550g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, ciuperci, \u0219unc\u0103, porumb (produs congelat), m\u0103sline...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">32,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-brasoveana\/\" data-quantity=\"1\" data-product_id=\"3488\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3488\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"418\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzacarnivora-600x418.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzacarnivora-600x418.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzacarnivora-300x209.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzacarnivora-768x535.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzacarnivora.webp 804w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-carnivora\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-carnivora\/\">Pizza Carnivora<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        500g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, ciuperci, \u0219unc\u0103, mu\u0219chi file, cabanos, salam de va...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">32,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-carnivora\/\" data-quantity=\"1\" data-product_id=\"3486\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3486\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"409\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzabadabing-600x409.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzabadabing-600x409.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzabadabing-300x205.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzabadabing-768x524.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzabadabing.webp 821w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-bada-bing\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-bada-bing\/\">Pizza Bada Bing<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        450g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, ceaf\u0103 afumat\u0103, ro\u0219ii felii, ardei gras\r\nAlergeni: ...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">32,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-bada-bing\/\" data-quantity=\"1\" data-product_id=\"3484\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3484\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaprosciuttofunghi-600x400.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaprosciuttofunghi-600x400.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaprosciuttofunghi-300x200.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaprosciuttofunghi-768x513.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaprosciuttofunghi.webp 839w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-prosciutto-e-funghi\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-prosciutto-e-funghi\/\">Pizza Prosciutto e Funghi<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        450g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, \u0219unc\u0103, ciuperci\r\nAlergeni: Gluten, Lapte, \u021aelin\u0103\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">30,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-prosciutto-e-funghi\/\" data-quantity=\"1\" data-product_id=\"3482\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3482\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzacasei-600x400.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzacasei-600x400.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzacasei-300x200.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzacasei-768x511.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzacasei.webp 841w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-casei\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-casei\/\">Pizza Casei<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        450g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, mu\u0219chi file, ciuperci, specialitate bacon\r\nAlergeni:...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">31,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-casei\/\" data-quantity=\"1\" data-product_id=\"3480\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3480\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzataraneasca-600x400.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzataraneasca-600x400.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzataraneasca-300x200.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzataraneasca-768x512.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzataraneasca.webp 840w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-taraneasca\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-taraneasca\/\">Pizza \u021a\u0103r\u0103neasc\u0103<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        520g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, \u0219unc\u0103, porumb (produs congelat), ardei gras, ceap\u0103...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">31,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-taraneasca\/\" data-quantity=\"1\" data-product_id=\"3478\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3478\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"398\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzatonno-600x398.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzatonno-600x398.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzatonno-300x199.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzatonno-768x510.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzatonno.webp 844w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-tonno\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-tonno\/\">Pizza Tonno<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        420g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, ton buc\u0103\u021bi \u00een suc propriu, ceap\u0103, l\u0103m\u00e2ie, m\u0103sl...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">35,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-tonno\/\" data-quantity=\"1\" data-product_id=\"3476\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3476\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaspeciala-600x400.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaspeciala-600x400.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaspeciala-300x200.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaspeciala-768x512.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaspeciala.webp 840w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-speciala\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-speciala\/\">Pizza Special\u0103<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        470g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, \u0219unc\u0103, ardei gras, porumb (produs congelat), legume...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">33,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-speciala\/\" data-quantity=\"1\" data-product_id=\"3474\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3474\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"373\" height=\"560\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzarustica.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzarustica.webp 373w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzarustica-200x300.webp 200w\" sizes=\"auto, (max-width: 373px) 100vw, 373px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-rustica\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-rustica\/\">Pizza Rustic\u0103<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        480g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, specialitate bacon, ciuperci, ardei iute, ardei gras,...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">33,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-rustica\/\" data-quantity=\"1\" data-product_id=\"3472\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3472\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"412\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaarcadia-600x412.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaarcadia-600x412.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaarcadia-300x206.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaarcadia-768x528.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaarcadia.webp 815w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-arcadia\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-arcadia\/\">Pizza Arcadia<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        400g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, \u0219unc\u0103, telemea, specialitate bacon, m\u0103sline negre ...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">32,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-arcadia\/\" data-quantity=\"1\" data-product_id=\"3468\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3468\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzamargherita-600x400.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzamargherita-600x400.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzamargherita-300x200.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzamargherita-768x512.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzamargherita.webp 840w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-margherita\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-margherita\/\">Pizza Margherita<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        450g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        extra topping pizza First\/mozzarella, sos de ro\u0219ii\r\nAlergeni: Gluten, Lapte, \u021aelin\u0103\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">29,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-margherita\/\" data-quantity=\"1\" data-product_id=\"3466\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3466\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/Bada-Bada-2-03704-600x400.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/Bada-Bada-2-03704-600x400.jpg 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/Bada-Bada-2-03704-300x200.jpg 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/Bada-Bada-2-03704-1024x683.jpg 1024w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/Bada-Bada-2-03704-768x512.jpg 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/Bada-Bada-2-03704-1536x1024.jpg 1536w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-3-formagio\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-3-formagio\/\">Pizza Quatro Formagio<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        450g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        extra topping pizza First\/mozzarella, sos de ro\u0219ii, telemea, parmezan, gorgonzola, ro\u0219ii felii\r\nAl...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">33,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-3-formagio\/\" data-quantity=\"1\" data-product_id=\"3464\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3464\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"412\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaprosciuttomuschiulet-600x412.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaprosciuttomuschiulet-600x412.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaprosciuttomuschiulet-300x206.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaprosciuttomuschiulet-768x527.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaprosciuttomuschiulet.webp 816w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-prosciutto-muschiulet\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-prosciutto-muschiulet\/\">Pizza Prosciutto Mu\u0219chiule\u021b<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        420g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, \u0219unc\u0103, mu\u0219chi file\r\nAlergeni: Gluten, Lapte, \u021aeli...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">31,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-prosciutto-muschiulet\/\" data-quantity=\"1\" data-product_id=\"3462\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3462\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"402\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzapepperoni-600x402.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzapepperoni-600x402.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzapepperoni-300x201.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzapepperoni-768x514.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzapepperoni.webp 836w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-pepperoni\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-pepperoni\/\">Pizza Pepperoni<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        430g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, salam Chorizo, telemea\r\nAlergeni: Gluten, Soia, Lapte...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">35,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-pepperoni\/\" data-quantity=\"1\" data-product_id=\"3460\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3460\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaprosciutto-600x400.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaprosciutto-600x400.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaprosciutto-300x200.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaprosciutto-768x512.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaprosciutto.webp 840w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-prosciutto-crudo\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-prosciutto-crudo\/\">Pizza Prosciutto Crudo<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        450g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, prosciutto crudo, rucola, parmezan\r\nAlergeni: Gluten,...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">37,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-prosciutto-crudo\/\" data-quantity=\"1\" data-product_id=\"3458\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3458\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"404\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaprosciuttosalami-600x404.webp\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaprosciuttosalami-600x404.webp 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaprosciuttosalami-300x202.webp 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaprosciuttosalami-768x518.webp 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/05\/pizzaprosciuttosalami.webp 831w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-prosciutto-salami\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-prosciutto-salami\/\">Pizza Prosciutto Salami<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                        450g                    <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        topping pizza First\/mozzarella, sos de ro\u0219ii, \u0219unc\u0103, m\u0103sline negre \u00eentregi, salam uscat\r\nAlerge...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">31,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/pizza-prosciutto-salami\/\" data-quantity=\"1\" data-product_id=\"3456\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3456\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>        <\/div>\n\t<\/div>\n<\/div>[\/vc_column][\/vc_row][vc_row sticker_svg_path=&#8221;&#8221; css=&#8221;.vc_custom_1751398103167{margin-top: 50px !important;}&#8221; el_class=&#8221;pizzaProduct&#8221;][vc_column][vc_empty_space height=&#8221;1px&#8221; el_id=&#8221;ofertasupercombo&#8221; el_class=&#8221;section-anchor&#8221;][vc_custom_heading text=&#8221;Oferta SUPER COMBO&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; google_fonts=&#8221;font_family:Open%20Sans%3A300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C800%2C800italic|font_style:800%20bold%20regular%3A800%3Anormal&#8221;]<div class=\"qodef-pl-holder qodef-grid-list qodef-disable-bottom-space qodef-standard-layout qodef-four-columns qodef-small-space qodef-info-below-image    qodef-filter-separator-enabled\"  data-type=standard data-info-position=info-below-image data-number-of-posts=999 data-number-of-columns=four data-space-between-items=small data-orderby=date data-order=DESC data-show-category-filter=no data-disable-filter-separator=no data-taxonomy-to-display=category data-taxonomy-values=SuperCombo data-show-all-item-in-filter=yes data-products-in-grid=yes data-display-title=yes data-title-tag=h5 data-display-category=no data-display-excerpt=no data-excerpt-length=20 data-display-rating=yes data-display-price=yes data-display-button=yes data-bg-image=no data-button-skin=default data-class-name=pli data-max-num-pages=1 data-next-page=2>\n            <div class=\"qodef-prl-loading\">\n        <div class=\"qodef-peppe-spinner-image\">\n<!--            -->        <\/div>\n    <\/div>\n\t<div class=\"qodef-pl-outer qodef-outer-space qodef-row-grid-section\">\n        <div class=\"qodef-outer-space\">\n            <div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"390\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/1-600x390.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/1-600x390.jpg 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/1-300x195.jpg 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/1-1024x666.jpg 1024w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/1-768x499.jpg 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/1.jpg 1181w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-1\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-1\/\">SUPER COMBO 1<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        - 1 Party Multipizza\r\n\r\n- 1 Party Carnivora\r\n\r\n- 2 Coca-Cola la 1l\r\n\r\n- 1 por\u021bie de Profiterol\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">180,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-1\/\" data-quantity=\"1\" data-product_id=\"3549\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3549\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"390\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/2-600x390.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/2-600x390.jpg 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/2-300x195.jpg 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/2-1024x665.jpg 1024w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/2-768x499.jpg 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/2.jpg 1181w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-2\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-2\/\">SUPER COMBO 2<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        - 1 Party Quatro Stagioni\r\n\r\n- 1 Party Bra\u0219ovean\u0103\r\n\r\n- 2 Coca-Cola la 1l\r\n\r\n- 1 por\u021bie de Profite...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">174,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-2\/\" data-quantity=\"1\" data-product_id=\"3547\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3547\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"390\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/3-600x390.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/3-600x390.jpg 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/3-300x195.jpg 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/3-1024x666.jpg 1024w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/3-768x499.jpg 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/3.jpg 1181w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-3\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-3\/\">SUPER COMBO 3<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        - 1 Party Bra\u0219ovean\u0103\r\n\r\n- 1 Party Deluxe\r\n\r\n- 2 Coca-Cola la 1l\r\n\r\n- 1 por\u021bie de Profiterol\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">184,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-3\/\" data-quantity=\"1\" data-product_id=\"3545\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3545\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"390\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/4-600x390.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/4-600x390.jpg 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/4-300x195.jpg 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/4-1024x666.jpg 1024w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/4-768x499.jpg 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/4.jpg 1181w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-4\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-4\/\">SUPER COMBO 4<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        - 1 Party Suprema\r\n\r\n- 1 Party \u021a\u0103r\u0103neasc\u0103\r\n\r\n- 2 Coca-Cola la 1l\r\n\r\n- 1 por\u021bie de Profiterol\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">180,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-4\/\" data-quantity=\"1\" data-product_id=\"3543\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3543\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"390\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/5-600x390.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/5-600x390.jpg 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/5-300x195.jpg 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/5-1024x666.jpg 1024w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/5-768x499.jpg 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/5.jpg 1181w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-5\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-5\/\">SUPER COMBO 5<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        - 1 Party Quatro Stagioni\r\n\r\n- 1 Party Prosciutto e Funghi\r\n\r\n- 1 Coca-Cola la 1l\r\n\r\n- 1 por\u021bie min...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">172,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-5\/\" data-quantity=\"1\" data-product_id=\"3539\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3539\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"390\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/6-600x390.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/6-600x390.jpg 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/6-300x195.jpg 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/6-1024x665.jpg 1024w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/6-768x499.jpg 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/6.jpg 1181w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-6\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-6\/\">SUPER COMBO 6<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        - 1 Party Multipizza\r\n\r\n- 1 Party Deluxe\r\n\r\n- 1 Coca-Cola la 1l\r\n\r\n- 1 por\u021bie mini eclere - 200g\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">199,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-6\/\" data-quantity=\"1\" data-product_id=\"3537\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3537\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"390\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/7-600x390.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/7-600x390.jpg 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/7-300x195.jpg 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/7-1024x666.jpg 1024w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/7-768x499.jpg 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/7.jpg 1181w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-7\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-7\/\">SUPER COMBO 7<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        - 1 Party Suprema\r\n\r\n- 1 Party Chicken Deluxe\r\n\r\n- 1 Coca-Cola la 1l\r\n\r\n- 1 por\u021bie mini eclere - 20...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">195,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-7\/\" data-quantity=\"1\" data-product_id=\"3535\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3535\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"390\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/8-600x390.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/8-600x390.jpg 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/8-300x195.jpg 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/8-1024x666.jpg 1024w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/8-768x499.jpg 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/8.jpg 1181w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-8\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-8\/\">SUPER COMBO 8<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        - 1 Party Prosciutto e Funghi\r\n\r\n- 1 Party Bra\u0219ovean\u0103\r\n\r\n- 1 Coca-Cola la 1l\r\n\r\n- 1 por\u021bie mini e...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">173,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-8\/\" data-quantity=\"1\" data-product_id=\"3533\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3533\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"390\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/9-600x390.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/9-600x390.jpg 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/9-300x195.jpg 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/9-1024x666.jpg 1024w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/9-768x499.jpg 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/9.jpg 1181w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-9\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-9\/\">SUPER COMBO 9<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        - 1 Party Margherita\r\n\r\n- 1 Party Carnivora\r\n\r\n- 1 sticl\u0103 de vin alb - Premiat\r\n\r\n- 1 sticl\u0103 de vi...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">191,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-9\/\" data-quantity=\"1\" data-product_id=\"3531\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3531\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"390\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/10-2-600x390.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/10-2-600x390.jpg 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/10-2-300x195.jpg 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/10-2-1024x665.jpg 1024w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/10-2-768x499.jpg 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/10-2.jpg 1181w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-10\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-10\/\">SUPER COMBO 10<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        - 1 Party Capriciosa\r\n\r\n- 1 Party Royal\r\n\r\n- 1 sticl\u0103 de vin alb - Premiat\r\n\r\n- 1 sticl\u0103 de vin ro...\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">191,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/super-combo-10\/\" data-quantity=\"1\" data-product_id=\"3529\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3529\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>        <\/div>\n\t<\/div>\n<\/div>[\/vc_column][\/vc_row][vc_row sticker_svg_path=&#8221;&#8221; css=&#8221;.vc_custom_1751398096433{margin-top: 50px !important;}&#8221;][vc_column][vc_empty_space height=&#8221;1px&#8221; el_id=&#8221;desert&#8221; el_class=&#8221;section-anchor&#8221;][vc_custom_heading text=&#8221;Desert&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; google_fonts=&#8221;font_family:Open%20Sans%3A300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C800%2C800italic|font_style:800%20bold%20regular%3A800%3Anormal&#8221;]<div class=\"qodef-pl-holder qodef-grid-list qodef-disable-bottom-space qodef-standard-layout qodef-four-columns qodef-small-space qodef-info-below-image    qodef-filter-separator-enabled\"  data-type=standard data-info-position=info-below-image data-number-of-posts=9999999 data-number-of-columns=four data-space-between-items=small data-orderby=date data-order=ASC data-show-category-filter=no data-disable-filter-separator=no data-taxonomy-to-display=category data-taxonomy-values=Desert data-show-all-item-in-filter=yes data-products-in-grid=yes data-display-title=yes data-title-tag=h5 data-display-category=no data-display-excerpt=no data-excerpt-length=20 data-display-rating=yes data-display-price=yes data-display-button=yes data-bg-image=no data-button-skin=default data-class-name=pli data-max-num-pages=1 data-next-page=2>\n            <div class=\"qodef-prl-loading\">\n        <div class=\"qodef-peppe-spinner-image\">\n<!--            -->        <\/div>\n    <\/div>\n\t<div class=\"qodef-pl-outer qodef-outer-space qodef-row-grid-section\">\n        <div class=\"qodef-outer-space\">\n            <div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"390\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/profiterol-600x390.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/profiterol-600x390.jpg 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/profiterol-300x195.jpg 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/profiterol-1024x666.jpg 1024w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/profiterol-768x500.jpg 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/profiterol.jpg 1182w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/profiterol\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/profiterol\/\">Profiterol &#8211; 200g<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        Alergeni: Gluten, Ou\u0103, Arahide, Soia, Lapte, Nuci\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">25,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"?add-to-cart=3586\" data-quantity=\"1\" data-product_id=\"3586\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Adaug\u0103 \u00een co\u0219<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3586\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"390\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2026\/06\/minieclere-600x390.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2026\/06\/minieclere-600x390.jpg 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2026\/06\/minieclere-300x195.jpg 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2026\/06\/minieclere-1024x666.jpg 1024w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2026\/06\/minieclere-768x500.jpg 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2026\/06\/minieclere.jpg 1182w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/mini-eclere-200g\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/mini-eclere-200g\/\">Mini Eclere &#8211; 200g<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        Alergeni: gluten, ou\u0103, lapte, soia, fructe cu coaj\u0103 lemnoas\u0103. Poate con\u021bine urme de arahide.\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">25,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"?add-to-cart=42749\" data-quantity=\"1\" data-product_id=\"42749\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Adaug\u0103 \u00een co\u0219<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"42749\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>        <\/div>\n\t<\/div>\n<\/div>[\/vc_column][\/vc_row][vc_row sticker_svg_path=&#8221;&#8221; css=&#8221;.vc_custom_1751398090343{margin-top: 50px !important;}&#8221;][vc_column][vc_empty_space height=&#8221;1px&#8221; el_id=&#8221;bauturi&#8221; el_class=&#8221;section-anchor&#8221;][vc_custom_heading text=&#8221;Bauturi&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; google_fonts=&#8221;font_family:Open%20Sans%3A300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C800%2C800italic|font_style:800%20bold%20regular%3A800%3Anormal&#8221;]<div class=\"qodef-pl-holder qodef-grid-list qodef-disable-bottom-space qodef-standard-layout qodef-four-columns qodef-small-space qodef-info-below-image    qodef-filter-separator-enabled\"  data-type=standard data-info-position=info-below-image data-number-of-posts=9999999999 data-number-of-columns=four data-space-between-items=small data-orderby=date data-order=DESC data-show-category-filter=no data-disable-filter-separator=no data-taxonomy-to-display=category data-taxonomy-values=Bauturi data-show-all-item-in-filter=yes data-products-in-grid=yes data-display-title=yes data-title-tag=h5 data-display-category=no data-display-excerpt=no data-excerpt-length=20 data-display-rating=yes data-display-price=yes data-display-button=yes data-bg-image=no data-button-skin=default data-class-name=pli data-max-num-pages=1 data-next-page=2>\n            <div class=\"qodef-prl-loading\">\n        <div class=\"qodef-peppe-spinner-image\">\n<!--            -->        <\/div>\n    <\/div>\n\t<div class=\"qodef-pl-outer qodef-outer-space qodef-row-grid-section\">\n        <div class=\"qodef-outer-space\">\n            <div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"196\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/cocacola33.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/coca-cola-4\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/coca-cola-4\/\">Coca-Cola 0,33l<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        \r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">8,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"?add-to-cart=3581\" data-quantity=\"1\" data-product_id=\"3581\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Adaug\u0103 \u00een co\u0219<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3581\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"196\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/fanta33.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/fanta-3\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/fanta-3\/\">Fanta 0,33l<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        \r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">8,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"?add-to-cart=3579\" data-quantity=\"1\" data-product_id=\"3579\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Adaug\u0103 \u00een co\u0219<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3579\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"196\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/sprite33.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/sprite-3\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/sprite-3\/\">Sprite 0,33l<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        \r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">8,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"?add-to-cart=3577\" data-quantity=\"1\" data-product_id=\"3577\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Adaug\u0103 \u00een co\u0219<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3577\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"196\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/cocacola125.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/coca-cola-3\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/coca-cola-3\/\">Coca-Cola 1l<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        \r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">15,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/coca-cola-3\/\" data-quantity=\"1\" data-product_id=\"3571\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3571\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"196\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/fanta125.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/fanta-2\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/fanta-2\/\">Fanta 1l<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        \r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">15,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/fanta-2\/\" data-quantity=\"1\" data-product_id=\"3569\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Select options<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3569\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"196\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/sprite125.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/sprite-2\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/sprite-2\/\">Sprite 1l<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        \r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">15,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"?add-to-cart=3567\" data-quantity=\"1\" data-product_id=\"3567\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Adaug\u0103 \u00een co\u0219<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3567\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"196\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/bereciuc.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/bere-ciuc-doza\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/bere-ciuc-doza\/\">Bere Ciuc 0,5l<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        \r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">12,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"?add-to-cart=3557\" data-quantity=\"1\" data-product_id=\"3557\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Adaug\u0103 \u00een co\u0219<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3557\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"196\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/vinalb.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/vin-alb-premiat-demisec\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/vin-alb-premiat-demisec\/\">Vin alb Premiat 0,7l<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        \r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">25,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"?add-to-cart=3553\" data-quantity=\"1\" data-product_id=\"3553\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Adaug\u0103 \u00een co\u0219<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3553\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"196\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/06\/vinrosu.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/vin-rosu-premiat-demisec\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/vin-rosu-premiat-demisec\/\">Vin rosu Premiat 0,7l<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        \r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">25,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"?add-to-cart=3551\" data-quantity=\"1\" data-product_id=\"3551\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Adaug\u0103 \u00een co\u0219<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3551\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>        <\/div>\n\t<\/div>\n<\/div>[\/vc_column][\/vc_row][vc_row sticker_svg_path=&#8221;&#8221; css=&#8221;.vc_custom_1751398084534{margin-top: 50px !important;}&#8221;][vc_column][vc_empty_space height=&#8221;1px&#8221; el_id=&#8221;sosuri&#8221; el_class=&#8221;section-anchor&#8221;][vc_custom_heading text=&#8221;Sosuri&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; google_fonts=&#8221;font_family:Open%20Sans%3A300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C800%2C800italic|font_style:800%20bold%20regular%3A800%3Anormal&#8221;]<div class=\"qodef-pl-holder qodef-grid-list qodef-disable-bottom-space qodef-standard-layout qodef-four-columns qodef-small-space qodef-info-below-image    qodef-filter-separator-enabled\"  data-type=standard data-info-position=info-below-image data-number-of-posts=9999999999 data-number-of-columns=four data-space-between-items=small data-orderby=date data-order=ASC data-show-category-filter=no data-disable-filter-separator=no data-taxonomy-to-display=category data-taxonomy-values=sosuri data-show-all-item-in-filter=yes data-products-in-grid=yes data-display-title=yes data-title-tag=h5 data-display-category=no data-display-excerpt=no data-excerpt-length=20 data-display-rating=yes data-display-price=yes data-display-button=yes data-bg-image=no data-button-skin=default data-class-name=pli data-max-num-pages=1 data-next-page=2>\n            <div class=\"qodef-prl-loading\">\n        <div class=\"qodef-peppe-spinner-image\">\n<!--            -->        <\/div>\n    <\/div>\n\t<div class=\"qodef-pl-outer qodef-outer-space qodef-row-grid-section\">\n        <div class=\"qodef-outer-space\">\n            <div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/sosdulce-1-600x400.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/sosdulce-1-600x400.jpg 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/sosdulce-1-300x200.jpg 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/sosdulce-1-768x512.jpg 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/sosdulce-1.jpg 901w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/sos-dulce\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/sos-dulce\/\">Sos dulce 80ml<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        \r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">6,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"?add-to-cart=3323\" data-quantity=\"1\" data-product_id=\"3323\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Adaug\u0103 \u00een co\u0219<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3323\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/sospicant-1-600x400.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/sospicant-1-600x400.jpg 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/sospicant-1-300x200.jpg 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/sospicant-1-768x512.jpg 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/sospicant-1.jpg 901w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/sos-picant\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/sos-picant\/\">Sos picant 80ml<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        \r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">6,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"?add-to-cart=3325\" data-quantity=\"1\" data-product_id=\"3325\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Adaug\u0103 \u00een co\u0219<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3325\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/sosusturoi-1-600x400.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/sosusturoi-1-600x400.jpg 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/sosusturoi-1-300x200.jpg 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/sosusturoi-1-768x512.jpg 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/sosusturoi-1.jpg 901w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/sos-de-usturoi\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/sos-de-usturoi\/\">Sos de usturoi 80ml<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        \r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">6,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"?add-to-cart=3327\" data-quantity=\"1\" data-product_id=\"3327\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Adaug\u0103 \u00een co\u0219<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3327\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"qodef-pli qodef-item-space \">\r\n    <div class=\"qodef-pli-inner\">\r\n        <div class=\"qodef-pli-image\">\r\n            \n<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/sosmaioneza-2-600x400.jpg\" class=\"attachment-woocommerce_single size-woocommerce_single wp-post-image\" alt=\"\" srcset=\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/sosmaioneza-2-600x400.jpg 600w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/sosmaioneza-2-300x200.jpg 300w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/sosmaioneza-2-768x512.jpg 768w, https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/04\/sosmaioneza-2.jpg 901w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>                        <a class=\"qodef-pli-link\" itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/sos-maioneza\/\"><\/a>\r\n        <\/div>\r\n        <div class=\"qodef-pli-text\" >\r\n            <div class=\"qodef-pli-text-outer testpizza\">\r\n\r\n                <div class=\"qodef-pli-text-inner\">\r\n                        <h5 itemprop=\"name\" class=\"entry-title qodef-pli-title\" >\n\t\t<a itemprop=\"url\" href=\"https:\/\/bada-bing.ro\/brasov\/index.php\/\/product\/sos-maioneza\/\">Sos maioneza 80ml<\/a>\n\t<\/h5>\n                    <div class=\"col-infoprod colGrame\">\r\n                                            <\/div>\r\n                    \r\n                                        <p class=\"exProd\">\r\n                        *contine gluten si praf de ou\r\n\r\n                    <\/p>\r\n                    <div class=\"wrp-alergeni\">\r\n                                                <div class=\"alergeni\" >\r\n                            \r\n                        <\/div>\r\n                        \r\n\r\n                    <\/div>\r\n\r\n\r\n\r\n                    \t\n\t<div class=\"qodef-pli-rating-holder\">\n\t\t<div class=\"qodef-pli-rating\" title=\"Rated %s out of 5\">\n\t\t\t<span style=\"width: 0%\"><\/span>\n\t\t<\/div>\n\t<\/div>\n                    <div class=\"wrapper-info-prod\">\r\n\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-price\"><span class=\"woocommerce-Price-amount amount\">6,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">lei<\/span><\/span><\/div>\n                        <\/div>\r\n                        <div class=\"col-infoprod\">\r\n                            \t<div class=\"qodef-pli-buttons\">\n        <div class=\"qodef-pli-add-to-cart qodef-default-skin\">\n            <a rel=\"nofollow\" href=\"?add-to-cart=3329\" data-quantity=\"1\" data-product_id=\"3329\" data-product_sku=\"\" class=\"button add_to_cart_button ajax_add_to_cart qodef-button\">Adaug\u0103 \u00een co\u0219<\/a>        <\/div>\n        <a href=\"#\" class=\"button yith-wcqv-button\" data-product_id=\"3329\">Alege<\/a>    <\/div>\n                        <\/div>\r\n                    <\/div>\r\n\r\n\r\n\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>        <\/div>\n\t<\/div>\n<\/div>[\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row sticker_svg_path=&#8221;&#8221; css=&#8221;.vc_custom_1688809733991{margin-top: 50px !important;}&#8221; el_class=&#8221;pizzaProduct&#8221;][vc_column][vc_empty_space height=&#8221;1px&#8221; el_id=&#8221;oferte&#8221; el_class=&#8221;section-anchor&#8221;][vc_custom_heading text=&#8221;Oferte&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; google_fonts=&#8221;font_family:Open%20Sans%3A300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C800%2C800italic|font_style:800%20bold%20regular%3A800%3Anormal&#8221;][\/vc_column][\/vc_row][vc_row sticker_svg_path=&#8221;&#8221; css=&#8221;.vc_custom_1751398121146{margin-top: 50px !important;}&#8221; el_class=&#8221;pizzaProduct&#8221;][vc_column][vc_empty_space height=&#8221;1px&#8221; el_id=&#8221;partytitan&#8221; el_class=&#8221;section-anchor&#8221;][vc_custom_heading text=&#8221;PIZZA PARTY TITAN (60&#215;80 cm | 10-14 persoane)&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; google_fonts=&#8221;font_family:Open%20Sans%3A300%2C300italic%2Cregular%2Citalic%2C600%2C600italic%2C700%2C700italic%2C800%2C800italic|font_style:800%20bold%20regular%3A800%3Anormal&#8221;][\/vc_column][\/vc_row][vc_row sticker_svg_path=&#8221;&#8221; css=&#8221;.vc_custom_1751398121146{margin-top: 50px !important;}&#8221; el_class=&#8221;pizzaProduct&#8221;][vc_column][vc_empty_space height=&#8221;1px&#8221; el_id=&#8221;pizzaparty&#8221; el_class=&#8221;section-anchor&#8221;][vc_custom_heading text=&#8221;PIZZA PARTY [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-3280","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pizza Bada Bing Brasov | Livrare pizza Brasov<\/title>\n<meta name=\"description\" content=\"Pizzeria Bada Bing, livrare pizza la domiciliu, plata numerar, card si tichete sau bonuri de masa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bada-bing.ro\/brasov\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pizza Bada Bing Brasov | Livrare pizza Brasov\" \/>\n<meta property=\"og:description\" content=\"Pizzeria Bada Bing, livrare pizza la domiciliu, plata numerar, card si tichete sau bonuri de masa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bada-bing.ro\/brasov\/\" \/>\n<meta property=\"og:site_name\" content=\"Bada Bing Brasov\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pizzabadabing\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-05T09:53:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Timp estimat pentru citire\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bada-bing.ro\/brasov\/\",\"url\":\"https:\/\/bada-bing.ro\/brasov\/\",\"name\":\"Pizza Bada Bing Brasov | Livrare pizza Brasov\",\"isPartOf\":{\"@id\":\"https:\/\/bada-bing.ro\/brasov\/#website\"},\"datePublished\":\"2023-03-20T19:05:51+00:00\",\"dateModified\":\"2025-07-05T09:53:23+00:00\",\"description\":\"Pizzeria Bada Bing, livrare pizza la domiciliu, plata numerar, card si tichete sau bonuri de masa\",\"breadcrumb\":{\"@id\":\"https:\/\/bada-bing.ro\/brasov\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bada-bing.ro\/brasov\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bada-bing.ro\/brasov\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\/\/bada-bing.ro\/brasov\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bada Bing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bada-bing.ro\/brasov\/#website\",\"url\":\"https:\/\/bada-bing.ro\/brasov\/\",\"name\":\"Bada Bing Brasov\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/bada-bing.ro\/brasov\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bada-bing.ro\/brasov\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bada-bing.ro\/brasov\/#organization\",\"name\":\"Bada Bing Brasov\",\"url\":\"https:\/\/bada-bing.ro\/brasov\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\/\/bada-bing.ro\/brasov\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/03\/logo.png\",\"contentUrl\":\"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/03\/logo.png\",\"width\":224,\"height\":84,\"caption\":\"Bada Bing Brasov\"},\"image\":{\"@id\":\"https:\/\/bada-bing.ro\/brasov\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pizzabadabing\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pizza Bada Bing Brasov | Livrare pizza Brasov","description":"Pizzeria Bada Bing, livrare pizza la domiciliu, plata numerar, card si tichete sau bonuri de masa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bada-bing.ro\/brasov\/","og_locale":"ro_RO","og_type":"article","og_title":"Pizza Bada Bing Brasov | Livrare pizza Brasov","og_description":"Pizzeria Bada Bing, livrare pizza la domiciliu, plata numerar, card si tichete sau bonuri de masa","og_url":"https:\/\/bada-bing.ro\/brasov\/","og_site_name":"Bada Bing Brasov","article_publisher":"https:\/\/www.facebook.com\/pizzabadabing","article_modified_time":"2025-07-05T09:53:23+00:00","twitter_card":"summary_large_image","twitter_misc":{"Timp estimat pentru citire":"2 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bada-bing.ro\/brasov\/","url":"https:\/\/bada-bing.ro\/brasov\/","name":"Pizza Bada Bing Brasov | Livrare pizza Brasov","isPartOf":{"@id":"https:\/\/bada-bing.ro\/brasov\/#website"},"datePublished":"2023-03-20T19:05:51+00:00","dateModified":"2025-07-05T09:53:23+00:00","description":"Pizzeria Bada Bing, livrare pizza la domiciliu, plata numerar, card si tichete sau bonuri de masa","breadcrumb":{"@id":"https:\/\/bada-bing.ro\/brasov\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bada-bing.ro\/brasov\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bada-bing.ro\/brasov\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/bada-bing.ro\/brasov\/"},{"@type":"ListItem","position":2,"name":"Bada Bing"}]},{"@type":"WebSite","@id":"https:\/\/bada-bing.ro\/brasov\/#website","url":"https:\/\/bada-bing.ro\/brasov\/","name":"Bada Bing Brasov","description":"","publisher":{"@id":"https:\/\/bada-bing.ro\/brasov\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bada-bing.ro\/brasov\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"},{"@type":"Organization","@id":"https:\/\/bada-bing.ro\/brasov\/#organization","name":"Bada Bing Brasov","url":"https:\/\/bada-bing.ro\/brasov\/","logo":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/bada-bing.ro\/brasov\/#\/schema\/logo\/image\/","url":"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/03\/logo.png","contentUrl":"https:\/\/bada-bing.ro\/brasov\/wp-content\/uploads\/2023\/03\/logo.png","width":224,"height":84,"caption":"Bada Bing Brasov"},"image":{"@id":"https:\/\/bada-bing.ro\/brasov\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pizzabadabing"]}]}},"_links":{"self":[{"href":"https:\/\/bada-bing.ro\/brasov\/index.php\/wp-json\/wp\/v2\/pages\/3280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bada-bing.ro\/brasov\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bada-bing.ro\/brasov\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bada-bing.ro\/brasov\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bada-bing.ro\/brasov\/index.php\/wp-json\/wp\/v2\/comments?post=3280"}],"version-history":[{"count":41,"href":"https:\/\/bada-bing.ro\/brasov\/index.php\/wp-json\/wp\/v2\/pages\/3280\/revisions"}],"predecessor-version":[{"id":27426,"href":"https:\/\/bada-bing.ro\/brasov\/index.php\/wp-json\/wp\/v2\/pages\/3280\/revisions\/27426"}],"wp:attachment":[{"href":"https:\/\/bada-bing.ro\/brasov\/index.php\/wp-json\/wp\/v2\/media?parent=3280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}